{"id":25661,"date":"2025-03-16T18:24:50","date_gmt":"2025-03-16T17:24:50","guid":{"rendered":"https:\/\/niryo.com\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/"},"modified":"2026-03-29T07:20:16","modified_gmt":"2026-03-29T05:20:16","slug":"chemische-industrie","status":"publish","type":"page","link":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/","title":{"rendered":"Chemische Industrie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-20565\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6ea369 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"b6ea369\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e849cc7 elementor-widget elementor-widget-back_niryo_v2\" data-id=\"e849cc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"back_niryo_v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"back_v2\">\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9deeaba e-flex e-con-boxed e-con e-parent\" data-id=\"9deeaba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-add97dc e-con-full e-flex e-con e-child\" data-id=\"add97dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fff93d elementor-widget elementor-widget-button\" data-id=\"0fff93d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INDUSTRIEZWEIGE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e6a265 elementor-widget elementor-widget-heading\" data-id=\"0e6a265\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Chemische Industrie<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f1bff1 elementor-widget elementor-widget-text-editor\" data-id=\"5f1bff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In der chemischen Industrie geh\u00f6ren Pr\u00e4zision, Sicherheit und Flexibilit\u00e4t zu den Grundvoraussetzungen. Niryo erf\u00fcllt diese Anforderungen durch die Bereitstellung von Roboterl\u00f6sungen, die auf Labore, Start-ups und KMUs in diesem Sektor zugeschnitten sind. Niryo optimiert die Handhabung von Chemikalien, das Abf\u00fcllen in Ampullen und sich wiederholende Aufgaben. F\u00fcr die organische Chemie erweist sich die Automatisierung als vorteilhaft, da sie die Zuverl\u00e4ssigkeit erh\u00f6ht und die strikte Einhaltung von Verfahrensanweisungen sicherstellt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-597dc52 e-con-full e-flex e-con e-child\" data-id=\"597dc52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15ee83f elementor-align-center elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"15ee83f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/niryo.com\/de\/nate-platform\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unsere Industriel\u00f6sungen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec77d07 e-con-full e-flex e-con e-child\" data-id=\"ec77d07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3b8171 elementor-widget elementor-widget-image\" data-id=\"e3b8171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"619\" height=\"674\" src=\"https:\/\/niryo.com\/wp-content\/uploads\/2026\/03\/Electronics.png\" class=\"attachment-full size-full wp-image-39847\" alt=\"\" srcset=\"https:\/\/niryo.com\/wp-content\/uploads\/2026\/03\/Electronics.png 619w, https:\/\/niryo.com\/wp-content\/uploads\/2026\/03\/Electronics-276x300.png 276w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d67dd0e e-con-full elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile e-flex e-con e-child\" data-id=\"d67dd0e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7937c elementor-widget elementor-widget-image\" data-id=\"5d7937c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"144\" height=\"40\" src=\"https:\/\/niryo.com\/wp-content\/uploads\/2025\/03\/saint-quentin-routage.png\" class=\"attachment-large size-large wp-image-25649\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0866284 elementor-widget elementor-widget-image\" data-id=\"0866284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"40\" src=\"https:\/\/niryo.com\/wp-content\/uploads\/2025\/03\/veolog.png\" class=\"attachment-large size-large wp-image-25650\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53160f2 e-flex e-con-boxed e-con e-parent\" data-id=\"53160f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aca54ee elementor-widget elementor-widget-heading\" data-id=\"aca54ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Vorteile<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99c37c6 elementor-widget elementor-widget-heading\" data-id=\"99c37c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Niryo in Ihrem Sektor.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8847ef9 e-con-full e-flex e-con e-child\" data-id=\"8847ef9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-72f055c e-con-full e-flex e-con e-child\" data-id=\"72f055c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6f033a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f6f033a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"41\" viewBox=\"0 0 40 41\" fill=\"none\"><g clip-path=\"url(#clip0_2706_5990)\"><path d=\"M1 4.9375H19\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-linejoin=\"round\"><\/path><path d=\"M29.5 4.9375L39 4.9375\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-linejoin=\"round\"><\/path><path d=\"M24.95 5.06042C24.95 6.28185 23.9517 7.27708 22.7265 7.27708C21.5012 7.27708 20.5029 6.28185 20.5029 5.06042C20.5029 3.83899 21.5012 2.84375 22.7265 2.84375C23.9517 2.84375 24.95 3.83899 24.95 5.06042Z\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M1 17.9375L14 17.9375\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-linejoin=\"round\"><\/path><path d=\"M29 17.9375L39 17.9375\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-linejoin=\"round\"><\/path><path d=\"M1 11.9375H5.5\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-linejoin=\"round\"><\/path><path d=\"M17 11.9375L39 11.9375\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"square\" stroke-linejoin=\"round\"><\/path><path d=\"M15.2205 11.6542C15.2205 12.8756 14.2222 13.8708 12.997 13.8708C11.7718 13.8708 10.7734 12.8756 10.7734 11.6542C10.7734 10.4327 11.7718 9.4375 12.997 9.4375C14.2222 9.4375 15.2205 10.4327 15.2205 11.6542Z\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M20.2217 29.3519V16.9567C20.2217 16.1514 20.857 15.5 21.6375 15.5C22.418 15.5 23.0533 16.1605 23.0533 16.9567V24.3938\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M25.8846 24.493V23.4254C25.8846 22.6202 25.2493 21.9688 24.4688 21.9688H23.1982\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M28.7252 24.9984V23.9489C28.7252 23.1436 28.09 22.4922 27.3094 22.4922H25.6123\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M29.4151 39.0337V35.9756C30.5405 34.7632 31.0578 33.6594 31.2302 31.4156L31.439 25.1637C31.4571 24.3313 30.9126 23.707 30.1321 23.707H28.8252\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M18.6693 27.1265L18.0431 26.5927C17.2989 25.9323 16.8179 25.7965 16.5547 25.7151C16.2915 25.6337 15.992 25.6246 15.992 25.6246C15.2659 25.507 14.5308 26.0861 14.7577 26.7827L20.1486 35.957C20.1486 35.957 20.6296 36.6175 20.6296 37.0608V39.0332\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_2706_5990\"><rect width=\"40\" height=\"40\" fill=\"white\" transform=\"translate(0 0.9375)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f09a12f elementor-widget elementor-widget-heading\" data-id=\"f09a12f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Automatisierung f\u00fcr jedermann<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe8fffe elementor-widget elementor-widget-text-editor\" data-id=\"fe8fffe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNiryo bietet eine erschwingliche und flexible L\u00f6sung, die ideal f\u00fcr Unternehmen in der chemischen Industrie ist. Die z\u00fcgige Implementierung und die benutzerfreundliche Programmierung erm\u00f6glichen eine nahtlose Automatisierung Ihrer Prozesse, ohne Ihre bestehende Arbeitsumgebung zu beeintr\u00e4chtigen. Zudem k\u00f6nnen Ihre Mitarbeiter und Techniker den Roboter eigenst\u00e4ndig bedienen. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-939e0df e-con-full e-flex e-con e-child\" data-id=\"939e0df\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-777b168 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"777b168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41\" height=\"40\" viewBox=\"0 0 41 40\" fill=\"none\"><g clip-path=\"url(#clip0_2793_21301)\"><path d=\"M17.4551 30.5048C18.3718 31.0477 19.3641 31.4667 20.413 31.7429L21.1029 35.8286H25.4123L26.1022 31.7429C27.1606 31.4667 28.1624 31.0477 29.0791 30.4953L32.415 32.9048L35.4675 29.8286L33.0766 26.4667C33.6247 25.5429 34.0405 24.5334 34.3146 23.4667L38.3782 22.7715V18.4286L34.324 17.7334C34.05 16.6667 33.6341 15.6572 33.086 14.7238L35.477 11.3619L32.4245 8.28575L29.0885 10.6953C28.1624 10.1429 27.1512 9.71432 26.0833 9.43813L25.4218 5.35242H21.1124L20.8383 7.31432\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M19.5715 21.9143C19.4298 21.5048 19.3447 21.0572 19.3447 20.6C19.3447 18.4191 21.1025 16.6476 23.2666 16.6476C25.4308 16.6476 27.1885 18.4191 27.1885 20.6C27.1885 22.781 25.4308 24.5524 23.2666 24.5524C22.5862 24.5524 21.9341 24.3715 21.3766 24.0667\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M13.1744 4.22858C13.1744 6.03811 11.719 7.50477 9.92347 7.50477C8.1279 7.50477 6.66309 6.03811 6.66309 4.22858C6.66309 2.41906 8.11845 0.952393 9.92347 0.952393C11.7285 0.952393 13.1744 2.41906 13.1744 4.22858Z\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M9.91406 25.8286V39.0477\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M5.62305 16.2285V39.0476\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M14.2142 39.0476V14.4476H18.5991C20.9712 14.4476 22.918 13.0381 22.918 10.6476V10.5428H6.59715C4.2251 10.5428 2.27832 12.5048 2.27832 14.8952V22.2857C2.27832 24.6762 3.23281 26.6381 5.60486 26.6381\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_2793_21301\"><rect width=\"40\" height=\"40\" fill=\"white\" transform=\"translate(0.333008)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0979324 elementor-widget elementor-widget-heading\" data-id=\"0979324\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Optimierung der Humanressourcen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-790fe2f elementor-widget elementor-widget-text-editor\" data-id=\"790fe2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDurch die Automatisierung sich wiederholender Aufgaben senken Sie die Arbeitskosten und erm\u00f6glichen es Ihren hochqualifizierten Technikern und Bedienern, sich auf Aufgaben mit h\u00f6herer Wertsch\u00f6pfung zu konzentrieren. Eine Schl\u00fcssell\u00f6sung zur Verbesserung der Effizienz und Produktivit\u00e4t Ihrer Teams. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35c3561 e-con-full e-flex e-con e-child\" data-id=\"35c3561\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39935c2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"39935c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41\" height=\"41\" viewBox=\"0 0 41 41\" fill=\"none\"><g clip-path=\"url(#clip0_2706_11225)\"><path d=\"M35.6665 24.1777C35.6665 32.8801 20.6665 39.9375 20.6665 39.9375C20.6665 39.9375 5.6665 32.8801 5.6665 24.1777V9.79043C10.2983 9.79043 14.7944 8.08693 18.3506 4.96223L20.6665 2.9375L22.9824 4.96223C26.5483 8.0772 31.0347 9.79043 35.6665 9.79043V24.1777Z\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"square\"><\/path><path d=\"M28.557 21.9423C28.557 21.4402 28.5063 20.9476 28.4048 20.4744L30.6665 18.852C30.2101 17.5 29.4495 16.2832 28.4758 15.2499L25.8693 16.3025C25.0986 15.6555 24.1959 15.1533 23.202 14.8347L22.8572 12.1596C22.1472 12.0148 21.417 11.9375 20.6665 11.9375C19.916 11.9375 19.1858 12.0148 18.4758 12.1596L18.131 14.8347C17.1371 15.1533 16.2345 15.6555 15.4637 16.3025L12.8572 15.2499C11.8835 16.2832 11.133 17.5 10.6665 18.852L12.9282 20.4744C12.8267 20.9476 12.776 21.4402 12.776 21.9423C12.776 22.4445 12.8267 22.937 12.9282 23.4102L10.6665 25.023C11.1229 26.375 11.8835 27.5918 12.8572 28.6251L15.4637 27.5725C16.2345 28.2195 17.1371 28.7217 18.131 29.0403L18.4758 31.7154C19.1858 31.8602 19.916 31.9375 20.6665 31.9375C21.417 31.9375 22.1472 31.8602 22.8572 31.7154L23.202 29.0403C24.1959 28.7217 25.0986 28.2195 25.8693 27.5725L28.4758 28.6251C29.4495 27.5918 30.2 26.375 30.6665 25.023L28.4048 23.4102C28.5063 22.937 28.557 22.4445 28.557 21.9423ZM20.6766 25.5058C18.6077 25.5058 16.9343 23.9124 16.9343 21.9423C16.9343 19.9723 18.6077 18.3788 20.6766 18.3788C22.7456 18.3788 24.419 19.9723 24.419 21.9423C24.419 23.9124 22.7456 25.5058 20.6766 25.5058Z\" stroke=\"#FF6825\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"square\"><\/path><\/g><defs><clipPath id=\"clip0_2706_11225\"><rect width=\"40\" height=\"40\" fill=\"white\" transform=\"translate(0.666504 0.9375)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f34308b elementor-widget elementor-widget-heading\" data-id=\"f34308b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Konformit\u00e4t und Sicherheit garantiert<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b49a9c elementor-widget elementor-widget-text-editor\" data-id=\"8b49a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIn der chemischen Industrie gelten strenge Standards. Unsere kollaborativen Roboter integrieren sich sicher in Ihre Prozesse, erf\u00fcllen die gesetzlichen Anforderungen und gew\u00e4hrleisten gleichzeitig eine pr\u00e4zise und zuverl\u00e4ssige Handhabung von Substanzen und Ger\u00e4ten. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c1924f e-flex e-con-boxed e-con e-parent\" data-id=\"7c1924f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1fe9ca elementor-widget elementor-widget-heading\" data-id=\"f1fe9ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">ANWENDUNGSFALL<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9caa64 elementor-widget elementor-widget-heading\" data-id=\"d9caa64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Anwendungsbeispiele<br>in der chemischen Industrie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7f978c elementor-widget elementor-widget-text-editor\" data-id=\"c7f978c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDank ihrer Flexibilit\u00e4t und Anpassungsf\u00e4higkeit an unterschiedliche Prozesse erf\u00fcllen die Niryo-Roboter die strengen Anforderungen der chemischen Industrie. Ob pr\u00e4zises Dosieren, das Abf\u00fcllen von Ampullen, das Aufschrauben von Verschl\u00fcssen oder die Qualit\u00e4tskontrolle: Niryo l\u00e4sst sich nahtlos in Ihre bestehende Umgebung integrieren, ohne Ihre Abl\u00e4ufe zu unterbrechen. Dabei wird h\u00f6chste Zuverl\u00e4ssigkeit sowie die Einhaltung aller Sicherheitsstandards gew\u00e4hrleistet. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-874c57b e-con-full e-flex e-con e-child\" data-id=\"874c57b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-53993b1 e-con-full e-flex e-con e-child\" data-id=\"53993b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2abacb9 elementor-widget elementor-widget-button\" data-id=\"2abacb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">REZEPTURMISCHUNG<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-453d38d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"453d38d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Genaue Dosierung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Homogenes Sch\u00fctteln<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Batch-Vorbereitung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e80ed5 e-con-full e-flex e-con e-child\" data-id=\"6e80ed5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b95dc3 elementor-widget elementor-widget-button\" data-id=\"4b95dc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">EINSPRITZUNG VON FL\u00dcSSIGKEITEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4937540 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4937540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Volumetrisches Abf\u00fcllen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mikrodosierung in Phiolen und Reagenzgl\u00e4sern<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wiederholte Einspritzung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d875ff0 e-con-full e-flex e-con e-child\" data-id=\"d875ff0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d05e26 elementor-widget elementor-widget-button\" data-id=\"6d05e26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">AUFSCHRAUBEN VON VERSCHL\u00dcSSEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18357e3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"18357e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kapselung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hermetische Versiegelung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Drehmomentkontrolliertes Anziehen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96eff5d e-con-full e-flex e-con e-child\" data-id=\"96eff5d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-035c4f4 e-con-full e-flex e-con e-child\" data-id=\"035c4f4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bfc16f elementor-widget elementor-widget-button\" data-id=\"7bfc16f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INTERAKTION MIT MASCHINEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf39dff elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cf39dff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bewegen von Produkten unter einem Abzug<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Automatisierung von Testzyklen <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00dcberf\u00fchrung auf Magnetr\u00fchrer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf27b58 e-con-full e-flex e-con e-child\" data-id=\"cf27b58\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9fb03e elementor-widget elementor-widget-button\" data-id=\"e9fb03e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ETIKETTIERUNG<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583b385 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"583b385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Etikettenanbringung per Kontaktverfahren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Etikettenanbringung mittels Einblasverfahren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00fcckverfolgbarkeit des Produkts<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40fe76e e-con-full e-flex e-con e-child\" data-id=\"40fe76e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fbbd74 elementor-widget elementor-widget-button\" data-id=\"3fbbd74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VERPACKUNG AM ENDE DER FERTIGUNGSLINIE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b9d684 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8b9d684\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prim\u00e4rverpackung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sekund\u00e4rverpackung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"arrow right\"><path id=\"icon\" d=\"M20 12L4 12M20 12L17 9M20 12L17 15\" stroke=\"#1865FF\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einpacken in Schachteln<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75d8533 e-flex e-con-boxed e-con e-parent\" data-id=\"75d8533\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e6c131 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7e6c131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Support and services to secure your automation projects<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d86ce4a e-con-full e-flex e-con e-child\" data-id=\"d86ce4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-aa8270a e-con-full e-flex e-con e-child\" data-id=\"aa8270a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d79f440 elementor-widget elementor-widget-heading\" data-id=\"d79f440\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Customer Success Management<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b7fb34 elementor-widget elementor-widget-text-editor\" data-id=\"8b7fb34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A team of experts who assist you throughout your project.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8812978 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8812978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Support throughout your project<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fast assistance and dedicated support<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Easy handling and increased skills<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Achieving your operational objectives<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Included in the price of the robot<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f66f740 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"f66f740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/niryo-succes-fuer-den-industriesektor\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover the service<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-253d747 e-con-full e-flex e-con e-child\" data-id=\"253d747\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90057e4 elementor-widget elementor-widget-heading\" data-id=\"90057e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Niryo Integration<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faab981 elementor-widget elementor-widget-text-editor\" data-id=\"faab981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Your expert automation partner.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e05c5d elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5e05c5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Audit and framing of needs<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prototyping and ROI validation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Systems design and integration<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Installation and commissioning<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Team training<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"8\" viewBox=\"0 0 19 8\" fill=\"none\"><path d=\"M17.5 4L1.5 4M17.5 4L14.5 1M17.5 4L14.5 7\" stroke=\"#FF6825\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Maintenance and performance monitoring<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4720f4c elementor-align-left elementor-widget elementor-widget-button\" data-id=\"4720f4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/niryo-integration-frankreich\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover the service<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-952ea2f e-flex e-con-boxed e-con e-parent\" data-id=\"952ea2f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4d77702 e-con-full e-flex e-con e-child\" data-id=\"4d77702\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6ecebde e-con-full e-flex e-con e-child\" data-id=\"6ecebde\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df55a07 elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"df55a07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"txt-orange\">Do you have<\/span>  an industrial robotics project?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdc690c e-con-full elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet e-flex e-con e-child\" data-id=\"cdc690c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61c080d elementor-widget elementor-widget-heading\" data-id=\"61c080d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"txt-orange\">Do you have<\/span>  an industrial robotics project?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e1c66f elementor-widget elementor-widget-text-editor\" data-id=\"0e1c66f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Complete the form to speak with our experts and obtain a recommendation adapted to your industrial needs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-367834a e-con-full e-flex e-con e-child\" data-id=\"367834a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c37f92e elementor-widget elementor-widget-heading\" data-id=\"c37f92e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Talk to an expert<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262c36d elementor-widget elementor-widget-html\" data-id=\"262c36d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script src=\"https:\/\/js.hsforms.net\/forms\/embed\/9158560.js\" defer><\/script>\n<div class=\"hs-form-frame\" data-region=\"na1\" data-form-id=\"a50a1dc2-425e-415f-802e-8939f1996e9e\" data-portal-id=\"9158560\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Back INDUSTRIEZWEIGE Chemische Industrie In der chemischen Industrie geh\u00f6ren Pr\u00e4zision, Sicherheit und Flexibilit\u00e4t zu den Grundvoraussetzungen. Niryo erf\u00fcllt diese Anforderungen durch die Bereitstellung von Roboterl\u00f6sungen, die auf Labore, Start-ups und KMUs in diesem Sektor zugeschnitten sind. Niryo optimiert die Handhabung von Chemikalien, das Abf\u00fcllen in Ampullen und sich wiederholende Aufgaben. F\u00fcr die organische Chemie erweist [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":25622,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-25661","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Automatisieren Sie Aufgaben in der chemischen Industrie mit Industrierobotern - Niryo<\/title>\n<meta name=\"description\" content=\"Verbessern Sie Pr\u00e4zision, Sicherheit und Flexibilit\u00e4t. Niryo-Roboter optimieren die Handhabung, Abf\u00fcllung und Automatisierung in Labors, Start-ups und KMUs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Automatisieren Sie Aufgaben in der chemischen Industrie mit Industrierobotern - Niryo\" \/>\n<meta property=\"og:description\" content=\"Verbessern Sie Pr\u00e4zision, Sicherheit und Flexibilit\u00e4t. Niryo-Roboter optimieren die Handhabung, Abf\u00fcllung und Automatisierung in Labors, Start-ups und KMUs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/\" \/>\n<meta property=\"og:site_name\" content=\"Niryo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-29T05:20:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niryo.com\/wp-content\/uploads\/2026\/03\/Electronics.png\" \/>\n\t<meta property=\"og:image:width\" content=\"619\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-fuer-die-industrie\\\/industriezweige\\\/chemische-industrie\\\/\",\"url\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-fuer-die-industrie\\\/industriezweige\\\/chemische-industrie\\\/\",\"name\":\"Automatisieren Sie Aufgaben in der chemischen Industrie mit Industrierobotern - Niryo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-fuer-die-industrie\\\/industriezweige\\\/chemische-industrie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-fuer-die-industrie\\\/industriezweige\\\/chemische-industrie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Electronics.png\",\"datePublished\":\"2025-03-16T17:24:50+00:00\",\"dateModified\":\"2026-03-29T05:20:16+00:00\",\"description\":\"Verbessern Sie Pr\u00e4zision, Sicherheit und Flexibilit\u00e4t. Niryo-Roboter optimieren die Handhabung, Abf\u00fcllung und Automatisierung in Labors, Start-ups und KMUs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-fuer-die-industrie\\\/industriezweige\\\/chemische-industrie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-fuer-die-industrie\\\/industriezweige\\\/chemische-industrie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-fuer-die-industrie\\\/industriezweige\\\/chemische-industrie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Electronics.png\",\"contentUrl\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Electronics.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-fuer-die-industrie\\\/industriezweige\\\/chemische-industrie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/niryo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00fcr die Industrie\",\"item\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-for-industry\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Industrielle Sektoren\",\"item\":\"https:\\\/\\\/niryo.com\\\/de\\\/niryo-for-industry\\\/industrial-sectors\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Chemische Industrie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/niryo.com\\\/de\\\/\",\"name\":\"Niryo\",\"description\":\"Robotics designed for what matters\",\"publisher\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/niryo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#organization\",\"name\":\"Niryo\",\"url\":\"https:\\\/\\\/niryo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Favicon-Niryo.svg\",\"contentUrl\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Favicon-Niryo.svg\",\"width\":512,\"height\":512,\"caption\":\"Niryo\"},\"image\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10970402\\\/admin\\\/feed\\\/posts\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@niryo_robotics\",\"https:\\\/\\\/www.instagram.com\\\/niryo_robotics\\\/\",\"https:\\\/\\\/discord.com\\\/invite\\\/EqpPYTf9FJ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Automatisieren Sie Aufgaben in der chemischen Industrie mit Industrierobotern - Niryo","description":"Verbessern Sie Pr\u00e4zision, Sicherheit und Flexibilit\u00e4t. Niryo-Roboter optimieren die Handhabung, Abf\u00fcllung und Automatisierung in Labors, Start-ups und KMUs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/","og_locale":"de_DE","og_type":"article","og_title":"Automatisieren Sie Aufgaben in der chemischen Industrie mit Industrierobotern - Niryo","og_description":"Verbessern Sie Pr\u00e4zision, Sicherheit und Flexibilit\u00e4t. Niryo-Roboter optimieren die Handhabung, Abf\u00fcllung und Automatisierung in Labors, Start-ups und KMUs.","og_url":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/","og_site_name":"Niryo","article_modified_time":"2026-03-29T05:20:16+00:00","og_image":[{"width":619,"height":674,"url":"https:\/\/niryo.com\/wp-content\/uploads\/2026\/03\/Electronics.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/","url":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/","name":"Automatisieren Sie Aufgaben in der chemischen Industrie mit Industrierobotern - Niryo","isPartOf":{"@id":"https:\/\/niryo.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/#primaryimage"},"image":{"@id":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/#primaryimage"},"thumbnailUrl":"https:\/\/niryo.com\/wp-content\/uploads\/2026\/03\/Electronics.png","datePublished":"2025-03-16T17:24:50+00:00","dateModified":"2026-03-29T05:20:16+00:00","description":"Verbessern Sie Pr\u00e4zision, Sicherheit und Flexibilit\u00e4t. Niryo-Roboter optimieren die Handhabung, Abf\u00fcllung und Automatisierung in Labors, Start-ups und KMUs.","breadcrumb":{"@id":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/#primaryimage","url":"https:\/\/niryo.com\/wp-content\/uploads\/2026\/03\/Electronics.png","contentUrl":"https:\/\/niryo.com\/wp-content\/uploads\/2026\/03\/Electronics.png"},{"@type":"BreadcrumbList","@id":"https:\/\/niryo.com\/de\/niryo-fuer-die-industrie\/industriezweige\/chemische-industrie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/niryo.com\/de\/"},{"@type":"ListItem","position":2,"name":"F\u00fcr die Industrie","item":"https:\/\/niryo.com\/de\/niryo-for-industry\/"},{"@type":"ListItem","position":3,"name":"Industrielle Sektoren","item":"https:\/\/niryo.com\/de\/niryo-for-industry\/industrial-sectors\/"},{"@type":"ListItem","position":4,"name":"Chemische Industrie"}]},{"@type":"WebSite","@id":"https:\/\/niryo.com\/de\/#website","url":"https:\/\/niryo.com\/de\/","name":"Niryo","description":"Robotics designed for what matters","publisher":{"@id":"https:\/\/niryo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niryo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/niryo.com\/de\/#organization","name":"Niryo","url":"https:\/\/niryo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/niryo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/niryo.com\/wp-content\/uploads\/2026\/02\/Favicon-Niryo.svg","contentUrl":"https:\/\/niryo.com\/wp-content\/uploads\/2026\/02\/Favicon-Niryo.svg","width":512,"height":512,"caption":"Niryo"},"image":{"@id":"https:\/\/niryo.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/10970402\/admin\/feed\/posts\/","https:\/\/www.tiktok.com\/@niryo_robotics","https:\/\/www.instagram.com\/niryo_robotics\/","https:\/\/discord.com\/invite\/EqpPYTf9FJ"]}]}},"_links":{"self":[{"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/pages\/25661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/comments?post=25661"}],"version-history":[{"count":0,"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/pages\/25661\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/pages\/25622"}],"wp:attachment":[{"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/media?parent=25661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}