{"id":26285,"date":"2024-04-24T10:56:52","date_gmt":"2024-04-24T08:56:52","guid":{"rendered":"https:\/\/niryo.com\/bedingungen-und-konditionen\/"},"modified":"2025-05-05T11:32:50","modified_gmt":"2025-05-05T09:32:50","slug":"bedingungen-und-konditionen","status":"publish","type":"page","link":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/","title":{"rendered":"Bedingungen und Konditionen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26285\" class=\"elementor elementor-26285 elementor-25\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2eb9e5 e-flex e-con-boxed e-con e-parent\" data-id=\"e2eb9e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2cfadc elementor-widget elementor-widget-back_niryo\" data-id=\"c2cfadc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"back_niryo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"back\">\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46b2b0c elementor-widget elementor-widget-heading\" data-id=\"46b2b0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#5391FF\">\/<\/span> Bedingungen und Konditionen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17a3c17 e-flex e-con-boxed e-con e-parent\" data-id=\"17a3c17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9457ff5 e-con-full e-flex e-con e-child\" data-id=\"9457ff5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-32d57b6 e-con-full e-flex e-con e-child\" data-id=\"32d57b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b35e6a2 elementor-widget elementor-widget-heading\" data-id=\"b35e6a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einf\u00fchrung\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0490cd0 elementor-widget elementor-widget-text-editor\" data-id=\"0490cd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie folgenden Allgemeinen Gesch\u00e4ftsbedingungen gelten f\u00fcr alle auf der niryo.com Webseite get\u00e4tigten K\u00e4ufe.\nNiryo (&#8222;wir&#8220;, &#8222;uns&#8220; oder &#8222;unser&#8220;) betreibt die niryo.com Webseite (&#8222;unsere Webseite&#8220;)\nBeachten Sie, dass die englischen &#8222;Terms and Conditions&#8220; eine \u00dcbersetzung der franz\u00f6sischen &#8222;Terms and Conditions&#8220; sind, die f\u00fcr Benutzer erstellt wurden, die die franz\u00f6sische Sprache nicht lesen k\u00f6nnen. Die anwendbaren &#8222;Allgemeinen Gesch\u00e4ftsbedingungen&#8220; sind die franz\u00f6sischen &#8222;Allgemeinen Gesch\u00e4ftsbedingungen&#8220;, die Sie auf niryo.com finden k\u00f6nnen, und das anwendbare Recht ist das franz\u00f6sische Recht. \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b3e93b e-con-full e-flex e-con e-child\" data-id=\"8b3e93b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e10a00 elementor-widget elementor-widget-heading\" data-id=\"7e10a00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 1 : Obligatorische Angaben\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbc81be elementor-widget elementor-widget-text-editor\" data-id=\"cbc81be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Website niryo.com ist ein Service von : Niryo SAS<\/p>\n<p>391 avenue Cl\u00e9ment Ader, 59118 Wambrechies, Frankreich<\/p>\n<p>Umsatzsteuer-Identifikationsnummer : FR79824143515<\/p>\n<p>Register f\u00fcr Handel und Gewerbe<\/p>\n<p>Gesellschaften: 824 143 515 R.C.S.<\/p>\n<p>Soziales Kapital : 10k\u20ac<\/p>\n<p>contact@niryo.com<\/p>\n<p>Webhosting : OVH SAS, 2 Rue Kellermann, 59100 ROUBAIX, Frankreich<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-deafef1 e-con-full e-flex e-con e-child\" data-id=\"deafef1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c8ba55 elementor-widget elementor-widget-heading\" data-id=\"2c8ba55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 2 : Verkaufte Produkte und Dienstleistungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e8eadf elementor-widget elementor-widget-text-editor\" data-id=\"0e8eadf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Website niryo.com verkauft<\/p>\n<p>L\u00f6sungen im Bereich Robotik, f\u00fcr Menschen und Unternehmen<\/p>\n<p>Und jede Aktivit\u00e4t oder Dienstleistung rund um diese Technologien<\/p>\n<p>Der Kunde erkl\u00e4rt sich mit den Allgemeinen Gesch\u00e4ftsbedingungen einverstanden, bevor er eine Bestellung abschlie\u00dft.<\/p>\n<p>Die Best\u00e4tigung Ihrer Bestellung bedeutet, dass Sie die Allgemeinen Gesch\u00e4ftsbedingungen akzeptieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77b13e5 e-con-full e-flex e-con e-child\" data-id=\"77b13e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-330f6d6 elementor-widget elementor-widget-heading\" data-id=\"330f6d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 3 : Preis\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2adf64d elementor-widget elementor-widget-text-editor\" data-id=\"2adf64d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Preise aller Produkte sind in Euro (\u20ac) ohne Steuern angegeben.<\/p>\n<p>Wenn Sie von au\u00dferhalb Frankreichs bestellen, ist der Kunde derjenige, der die Produkte, die er kauft, importiert. F\u00fcr jedes Produkt, das au\u00dferhalb der Europ\u00e4ischen Union versandt wird, weist die Rechnung den Preis ohne Steuern aus. Der Kunde ist f\u00fcr die Einfuhrsteuern in seinem eigenen Land\/Staat verantwortlich.  <\/p>\n<p>Der Versandpreis ist nicht im Produktpreis enthalten. Er wird an der Kasse berechnet und angezeigt, bevor Sie die Bestellung abschlie\u00dfen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a872de2 e-con-full e-flex e-con e-child\" data-id=\"a872de2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-913f075 elementor-widget elementor-widget-heading\" data-id=\"913f075\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 4 : Verf\u00fcgbarkeit der Produkte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9369b8 elementor-widget elementor-widget-text-editor\" data-id=\"f9369b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Verf\u00fcgbarkeit der Produkte wird h\u00e4ufig auf unserer Website aktualisiert.<\/p>\n<p>Wenn Sie ein Produkt bestellt haben, das nach der Validierung Ihrer Bestellung nicht verf\u00fcgbar ist, werden Sie umgehend informiert. Wir informieren Sie dann \u00fcber die Verz\u00f6gerung der Lieferung. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b4d4dc e-con-full e-flex e-con e-child\" data-id=\"5b4d4dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-886e625 elementor-widget elementor-widget-heading\" data-id=\"886e625\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 5 : Bestellung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23aba1e elementor-widget elementor-widget-text-editor\" data-id=\"23aba1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie k\u00f6nnen unsere Produkte direkt auf unserer Website oder per E-Mail (sales@niryo.com) bestellen. Um auf unserer Website zu bestellen, w\u00e4hlen Sie die gew\u00fcnschten Produkte aus und legen Sie sie in Ihren Warenkorb.<\/p>\n<p>Best\u00e4tigen Sie Ihren Warenkorb.<\/p>\n<p>Wenn Sie bereits auf unserer Website registriert sind, melden Sie sich bitte an. Wenn Sie noch nicht auf unserer Website registriert sind, registrieren Sie sich bitte. <\/p>\n<p>Falls verf\u00fcgbar, w\u00e4hlen Sie eine Versandart.<\/p>\n<p>W\u00e4hlen Sie eine Zahlungsmethode und akzeptieren Sie die Allgemeinen Gesch\u00e4ftsbedingungen.<\/p>\n<p>Best\u00e4tigen Sie Ihre Zahlung.<\/p>\n<p>Sie erhalten eine Best\u00e4tigungs-E-Mail f\u00fcr Ihre Bestellung an die E-Mail-Adresse, die Sie bei der Registrierung angegeben haben.<\/p>\n<p>Das Eigentum an den Produkten wird erst nach der vollst\u00e4ndigen Bezahlung Ihrer Bestellung \u00fcbertragen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0b2a76 e-con-full e-flex e-con e-child\" data-id=\"e0b2a76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f3002e elementor-widget elementor-widget-heading\" data-id=\"4f3002e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 6 : Schifffahrt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16a8d57 elementor-widget elementor-widget-text-editor\" data-id=\"16a8d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir versenden weltweit. Wir liefern ausschlie\u00dflich an die vom Kunden angegebene Lieferadresse. <\/p>\n<p>Die Produkte werden mit einem Spezialtransporter verschickt. Die Versandkosten und das Transportunternehmen h\u00e4ngen von der Lieferadresse und den bestellten Produkten ab. <\/p>\n<p>Die Lieferfrist ist eine Sch\u00e4tzung. Sie kann sich aufgrund einiger Faktoren entwickeln: Verf\u00fcgbarkeit unserer Spediteure, Auftragsabwicklung usw. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-01bd736 e-con-full e-flex e-con e-child\" data-id=\"01bd736\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d7bd1f elementor-widget elementor-widget-heading\" data-id=\"7d7bd1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 7 : Zahlungsmodalit\u00e4ten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-070d9af elementor-widget elementor-widget-text-editor\" data-id=\"070d9af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Es werden mehrere Zahlungsarten akzeptiert. Als Kunde k\u00f6nnen Sie per Kredit- oder Debitkarte, Paypal und Direkt\u00fcberweisung bezahlen. <\/p>\n<p>Wir akzeptieren Zahlungen mit Kredit- und Debitkarten. Die Online-Zahlung ist gesichert. <\/p>\n<p>Wir ben\u00f6tigen eine vollst\u00e4ndige Zahlung, um die Bestellung zu best\u00e4tigen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ba4863 e-con-full e-flex e-con e-child\" data-id=\"3ba4863\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48d238b elementor-widget elementor-widget-heading\" data-id=\"48d238b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 8 : Recht auf Widerruf<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a785cda elementor-widget elementor-widget-text-editor\" data-id=\"a785cda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sobald Sie Ihr Produkt erhalten haben, haben Sie ein 14-t\u00e4giges Widerrufsrecht.<\/p>\n<p>Beachten Sie, dass das Widerrufsrecht nicht f\u00fcr ma\u00dfgeschneiderte Produkte und Produkte gilt, die nach Ihren eigenen spezifischen Angaben hergestellt wurden. Vom Widerrufsrecht ausgeschlossen sind Produkte, die verderblich sind, die nicht dem Versand unterliegen (z.B. Downloads) oder die sich verschlechtern k\u00f6nnen. <\/p>\n<p>Schicken Sie das Produkt innerhalb des oben genannten Zeitraums zur\u00fcck. Machen Sie innerhalb desselben Zeitraums von Ihrem Widerrufsrecht Gebrauch, indem Sie sich schriftlich an 391 avenue Cl\u00e9ment Ader, 59118 Wambrechies, Frankreich, oder per E-Mail an support@niryo.com wenden. <\/p>\n<p>Die Produkte m\u00fcssen an die folgende Adresse zur\u00fcckgeschickt werden, die Kosten f\u00fcr die R\u00fccksendung gehen zu Ihren Lasten: Niryo, 391 avenue Cl\u00e9ment Ader, 59118 Wambrechies, Frankreich.<\/p>\n<p>Das zur\u00fcckgegebene Produkt muss in der Originalverpackung und in einwandfreiem Zustand sein. Die Verpackung kann ge\u00f6ffnet und das Produkt verwendet werden, solange wir es wieder verkaufen k\u00f6nnen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bbbc4c0 e-con-full e-flex e-con e-child\" data-id=\"bbbc4c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2f45f0 elementor-widget elementor-widget-heading\" data-id=\"b2f45f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 9 : Garantie und R\u00fcckgaberecht<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8115c71 elementor-widget elementor-widget-text-editor\" data-id=\"8115c71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie erhalten eine Konformit\u00e4tsgarantie gem\u00e4\u00df dem Gesetz (Artikel L211-4 des &#8222;Code de la consommation&#8220;)<\/p>\n<p>Die Garantie gilt f\u00fcr unsere neuen Produkte, die einen Mangel aufweisen (Fehlen bestimmter Funktionen, Fehlen der online angezeigten Eigenschaften, nicht normales Funktionieren des Produkts, Nichtfunktionieren des Produkts), und zwar ohne jegliche andere vertragliche Garantie. Im Falle eines Konformit\u00e4tsproblems verpflichten wir uns zu : <\/p>\n<p>Ersetzen Sie das Produkt<\/p>\n<p>Reparieren Sie das Produkt innerhalb von 30 Tagen, ohne zus\u00e4tzliche Kosten<\/p>\n<p>Wenn wir die Garantie nicht einhalten k\u00f6nnen, verpflichten wir uns, Ihnen den Gesamtpreis zu erstatten oder einen Teil des Preises, wenn Sie das Produkt behalten m\u00f6chten.<\/p>\n<p>Im Falle eines versteckten Mangels an Ihrem Produkt, der bereits vor Abschluss Ihrer Bestellung vorhanden war, verpflichten wir uns, Ihre Bestellung innerhalb kurzer Zeit zu reparieren, zu ersetzen oder den Kaufpreis zu erstatten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-259c59e e-con-full e-flex e-con e-child\" data-id=\"259c59e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e31b86b elementor-widget elementor-widget-heading\" data-id=\"e31b86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 10 : Erstattungsbedingungen und Verzug<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64aef54 elementor-widget elementor-widget-text-editor\" data-id=\"64aef54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie R\u00fcckerstattung eines Produkts bezieht sich auf den Gesamtbetrag des Produkts. Sie erfolgt per Direkt\u00fcberweisung \/ Paypal \/ etc. innerhalb von 30 Tagen nach dem Datum, an dem Sie Ihr Widerrufsrecht geltend gemacht haben. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-324c694 e-con-full e-flex e-con e-child\" data-id=\"324c694\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-861e0a0 elementor-widget elementor-widget-heading\" data-id=\"861e0a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 11 : Beschwerden von Kunden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-393adb1 elementor-widget elementor-widget-text-editor\" data-id=\"393adb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jede Kundenbeschwerde sollte an Niryo, 391 avenue Cl\u00e9ment Ader, 59118 Wambrechies, Frankreich, oder per E-Mail an support@niryo.com gesendet werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c310b48 e-con-full e-flex e-con e-child\" data-id=\"c310b48\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d146fa elementor-widget elementor-widget-heading\" data-id=\"1d146fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 12 : Geistiges Eigentum<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73050d5 elementor-widget elementor-widget-text-editor\" data-id=\"73050d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAlle Kommentare, Bilder und Illustrationen auf unserer Website sind ausschlie\u00dflich uns vorbehalten. Jegliche Nutzung ist verboten, au\u00dfer f\u00fcr den privaten Gebrauch. \n\nOhne unsere Genehmigung ist die teilweise oder vollst\u00e4ndige Reproduktion von Inhalten unserer Website\nstrengstens untersagt.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99977e5 e-con-full e-flex e-con e-child\" data-id=\"99977e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9c2a94 elementor-widget elementor-widget-heading\" data-id=\"e9c2a94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 13 : Verantwortung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae0ef7b elementor-widget elementor-widget-text-editor\" data-id=\"ae0ef7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wie in Artikel 1147 des Code Civil vorgesehen, \u00fcbernehmen wir die vertragliche Verantwortung im Falle einer nicht ordnungsgem\u00e4\u00dfen Erf\u00fcllung des unterzeichneten Vertrags. Au\u00dfer wenn : <\/p>\n<p>Fall von h\u00f6herer Gewalt<\/p>\n<p>Externe Ereignisse, f\u00fcr die wir nicht verantwortlich gemacht werden k\u00f6nnen<\/p>\n<p>Fotos \/ Illustrationen \/ Bilder auf unserer Website haben keinen vertraglichen Wert.<\/p>\n<p>Wir k\u00f6nnen daher nicht f\u00fcr eine Falschdarstellung haftbar gemacht werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dfa118 e-con-full e-flex e-con e-child\" data-id=\"1dfa118\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-546bdb4 elementor-widget elementor-widget-heading\" data-id=\"546bdb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 14 : Personenbezogene Daten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec7900 elementor-widget elementor-widget-text-editor\" data-id=\"4ec7900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Einige Daten des Kunden werden an den Verk\u00e4ufer \u00fcbermittelt (Name, Vorname, Adresse, Postleitzahl, Telefonnummer), um die Bestellung zu bearbeiten und die bestellten Produkte zu versenden.<\/p>\n<p>Die kommerziellen Angebote auf unserer Website werden dem Kunden per E-Mail zugesandt, wenn er keinen Widerspruch eingelegt hat. Der Kunde kann den Erhalt von Werbeangeboten jederzeit \u00fcber sein pers\u00f6nliches Konto oder schriftlich an Niryo, 391 avenue Cl\u00e9ment Ader, 59118 Wambrechies, Frankreich, ablehnen. <\/p>\n<p>Kundendaten k\u00f6nnen mit Zustimmung des Kunden an kommerzielle Partner der Website gesendet werden.<\/p>\n<p>Unsere Website gew\u00e4hrleistet den Schutz der Privatsph\u00e4re des Kunden bei der Erfassung und Verarbeitung personenbezogener Daten. Der Kunde hat das Recht, seine pers\u00f6nlichen Daten zu lesen, zu \u00e4ndern und zu l\u00f6schen. <\/p>\n<p>Der Client kann dies \u00fcber :<\/p>\n<p>Website-Konto<\/p>\n<p>Kontaktformular auf der Website<\/p>\n<p>Mail an contact@niryo.com<\/p>\n<p>Schreiben Sie an Niryo, 391 avenue Cl\u00e9ment Ader, 59118 Wambrechies, Frankreich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee96ad4 e-con-full e-flex e-con e-child\" data-id=\"ee96ad4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-784a140 elementor-widget elementor-widget-heading\" data-id=\"784a140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 15 : Anwendbares Recht<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5276ae elementor-widget elementor-widget-text-editor\" data-id=\"e5276ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im Falle eines Konflikts zwischen dem Kunden und unserem Unternehmen ist das franz\u00f6sische Recht anwendbar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ab18ec e-con-full e-flex e-con e-child\" data-id=\"3ab18ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4110058 elementor-widget elementor-widget-heading\" data-id=\"4110058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ARTIKEL 16 : \u00c4nderungen der Bedingungen und Konditionen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79ad600 elementor-widget elementor-widget-text-editor\" data-id=\"79ad600\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir behalten uns das Recht vor, unsere Allgemeinen Gesch\u00e4ftsbedingungen jederzeit zu \u00e4ndern. In diesem Fall gelten f\u00fcr die Bestellung eines Produkts durch einen Kunden die Allgemeinen Gesch\u00e4ftsbedingungen des Tages, an dem die Bestellung best\u00e4tigt wurde. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f4172c e-con-full elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile e-flex e-con e-child\" data-id=\"8f4172c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bde888d e-con-full e-flex e-con e-child\" data-id=\"bde888d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;],&quot;sticky_offset&quot;:20,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99b65f5 elementor-widget elementor-widget-table-of-contents\" data-id=\"99b65f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;no_headings_message&quot;:&quot;Es wurden keine \\u00dcberschriften auf dieser Seite gefunden.&quot;,&quot;min_height_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tZusammenfassung\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__99b65f5\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Back Einf\u00fchrung Die folgenden Allgemeinen Gesch\u00e4ftsbedingungen gelten f\u00fcr alle auf der niryo.com Webseite get\u00e4tigten K\u00e4ufe. Niryo (&#8222;wir&#8220;, &#8222;uns&#8220; oder &#8222;unser&#8220;) betreibt die niryo.com Webseite (&#8222;unsere Webseite&#8220;) Beachten Sie, dass die englischen &#8222;Terms and Conditions&#8220; eine \u00dcbersetzung der franz\u00f6sischen &#8222;Terms and Conditions&#8220; sind, die f\u00fcr Benutzer erstellt wurden, die die franz\u00f6sische Sprache nicht lesen k\u00f6nnen. Die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-26285","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bedingungen und Konditionen - Niryo<\/title>\n<meta name=\"description\" content=\"Entdecken Sie unsere Bedingungen und Konditionen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bedingungen und Konditionen - Niryo\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie unsere Bedingungen und Konditionen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Niryo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T09:32:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niryo.com\/wp-content\/plugins\/niryo\/assets\/icons\/left.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/bedingungen-und-konditionen\\\/\",\"url\":\"https:\\\/\\\/niryo.com\\\/de\\\/bedingungen-und-konditionen\\\/\",\"name\":\"Bedingungen und Konditionen - Niryo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/bedingungen-und-konditionen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/bedingungen-und-konditionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/plugins\\\/niryo\\\/assets\\\/icons\\\/left.svg\",\"datePublished\":\"2024-04-24T08:56:52+00:00\",\"dateModified\":\"2025-05-05T09:32:50+00:00\",\"description\":\"Entdecken Sie unsere Bedingungen und Konditionen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/bedingungen-und-konditionen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/niryo.com\\\/de\\\/bedingungen-und-konditionen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/bedingungen-und-konditionen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/plugins\\\/niryo\\\/assets\\\/icons\\\/left.svg\",\"contentUrl\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/plugins\\\/niryo\\\/assets\\\/icons\\\/left.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/bedingungen-und-konditionen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/niryo.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bedingungen und Konditionen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/niryo.com\\\/de\\\/\",\"name\":\"Niryo\",\"description\":\"Robotics designed for what matters\",\"publisher\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/niryo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#organization\",\"name\":\"Niryo\",\"url\":\"https:\\\/\\\/niryo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Favicon-Niryo.svg\",\"contentUrl\":\"https:\\\/\\\/niryo.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Favicon-Niryo.svg\",\"width\":512,\"height\":512,\"caption\":\"Niryo\"},\"image\":{\"@id\":\"https:\\\/\\\/niryo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10970402\\\/admin\\\/feed\\\/posts\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@niryo_robotics\",\"https:\\\/\\\/www.instagram.com\\\/niryo_robotics\\\/\",\"https:\\\/\\\/discord.com\\\/invite\\\/EqpPYTf9FJ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bedingungen und Konditionen - Niryo","description":"Entdecken Sie unsere Bedingungen und Konditionen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/","og_locale":"de_DE","og_type":"article","og_title":"Bedingungen und Konditionen - Niryo","og_description":"Entdecken Sie unsere Bedingungen und Konditionen.","og_url":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/","og_site_name":"Niryo","article_modified_time":"2025-05-05T09:32:50+00:00","og_image":[{"url":"https:\/\/niryo.com\/wp-content\/plugins\/niryo\/assets\/icons\/left.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/","url":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/","name":"Bedingungen und Konditionen - Niryo","isPartOf":{"@id":"https:\/\/niryo.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/#primaryimage"},"image":{"@id":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/#primaryimage"},"thumbnailUrl":"https:\/\/niryo.com\/wp-content\/plugins\/niryo\/assets\/icons\/left.svg","datePublished":"2024-04-24T08:56:52+00:00","dateModified":"2025-05-05T09:32:50+00:00","description":"Entdecken Sie unsere Bedingungen und Konditionen.","breadcrumb":{"@id":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/#primaryimage","url":"https:\/\/niryo.com\/wp-content\/plugins\/niryo\/assets\/icons\/left.svg","contentUrl":"https:\/\/niryo.com\/wp-content\/plugins\/niryo\/assets\/icons\/left.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/niryo.com\/de\/bedingungen-und-konditionen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/niryo.com\/de\/"},{"@type":"ListItem","position":2,"name":"Bedingungen und Konditionen"}]},{"@type":"WebSite","@id":"https:\/\/niryo.com\/de\/#website","url":"https:\/\/niryo.com\/de\/","name":"Niryo","description":"Robotics designed for what matters","publisher":{"@id":"https:\/\/niryo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niryo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/niryo.com\/de\/#organization","name":"Niryo","url":"https:\/\/niryo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/niryo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/niryo.com\/wp-content\/uploads\/2026\/02\/Favicon-Niryo.svg","contentUrl":"https:\/\/niryo.com\/wp-content\/uploads\/2026\/02\/Favicon-Niryo.svg","width":512,"height":512,"caption":"Niryo"},"image":{"@id":"https:\/\/niryo.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/10970402\/admin\/feed\/posts\/","https:\/\/www.tiktok.com\/@niryo_robotics","https:\/\/www.instagram.com\/niryo_robotics\/","https:\/\/discord.com\/invite\/EqpPYTf9FJ"]}]}},"_links":{"self":[{"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/pages\/26285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/comments?post=26285"}],"version-history":[{"count":0,"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/pages\/26285\/revisions"}],"wp:attachment":[{"href":"https:\/\/niryo.com\/de\/wp-json\/wp\/v2\/media?parent=26285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}